{"id":29,"count":27,"description":"","link":"https:\/\/www.peerspace.com\/resources\/tag\/camera-equipment\/","name":"camera equipment","slug":"camera-equipment","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Resources - Peerspace<\/title>\n<meta name=\"description\" content=\"Explore articles and videos on camera equipment. Get advice and ideas from the world&#039;s most creative people.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Resources - Peerspace\" \/>\n<meta property=\"og:description\" content=\"Explore articles and videos on camera equipment. Get advice and ideas from the world&#039;s most creative people.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.peerspace.com\/resources\/tag\/camera-equipment\/\" \/>\n<meta property=\"og:site_name\" content=\"Peerspace\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@peerspace\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.peerspace.com\\\/resources\\\/tag\\\/camera-equipment\\\/\",\"url\":\"https:\\\/\\\/www.peerspace.com\\\/resources\\\/tag\\\/camera-equipment\\\/\",\"name\":\"Resources - Peerspace\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.peerspace.com\\\/resources\\\/#website\"},\"description\":\"Explore articles and videos on camera equipment. Get advice and ideas from the world's most creative people.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.peerspace.com\\\/resources\\\/tag\\\/camera-equipment\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.peerspace.com\\\/resources\\\/tag\\\/camera-equipment\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.peerspace.com\\\/resources\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"camera equipment\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.peerspace.com\\\/resources\\\/#website\",\"url\":\"https:\\\/\\\/www.peerspace.com\\\/resources\\\/\",\"name\":\"Peerspace\",\"description\":\"Resources &amp; Inspiration to make every moment worth celebrating\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.peerspace.com\\\/resources\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.peerspace.com\\\/resources\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.peerspace.com\\\/resources\\\/#organization\",\"name\":\"Peerspace\",\"url\":\"https:\\\/\\\/www.peerspace.com\\\/resources\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.peerspace.com\\\/resources\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.peerspace.com\\\/resources\\\/wp-content\\\/uploads\\\/320180448_537730991614706_6776666821941108653_n.jpg\",\"contentUrl\":\"https:\\\/\\\/www.peerspace.com\\\/resources\\\/wp-content\\\/uploads\\\/320180448_537730991614706_6776666821941108653_n.jpg\",\"width\":800,\"height\":800,\"caption\":\"Peerspace\"},\"image\":{\"@id\":\"https:\\\/\\\/www.peerspace.com\\\/resources\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/peerspace\",\"https:\\\/\\\/x.com\\\/peerspace\",\"https:\\\/\\\/instagram.com\\\/peerspace\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/peerspace\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/peerspace\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCUP7_kldWXa7zRDge66pKfw\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Resources - Peerspace","description":"Explore articles and videos on camera equipment. Get advice and ideas from the world's most creative people.","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Resources - Peerspace","og_description":"Explore articles and videos on camera equipment. Get advice and ideas from the world's most creative people.","og_url":"https:\/\/www.peerspace.com\/resources\/tag\/camera-equipment\/","og_site_name":"Peerspace","twitter_card":"summary_large_image","twitter_site":"@peerspace","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.peerspace.com\/resources\/tag\/camera-equipment\/","url":"https:\/\/www.peerspace.com\/resources\/tag\/camera-equipment\/","name":"Resources - Peerspace","isPartOf":{"@id":"https:\/\/www.peerspace.com\/resources\/#website"},"description":"Explore articles and videos on camera equipment. Get advice and ideas from the world's most creative people.","breadcrumb":{"@id":"https:\/\/www.peerspace.com\/resources\/tag\/camera-equipment\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.peerspace.com\/resources\/tag\/camera-equipment\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.peerspace.com\/resources\/"},{"@type":"ListItem","position":2,"name":"camera equipment"}]},{"@type":"WebSite","@id":"https:\/\/www.peerspace.com\/resources\/#website","url":"https:\/\/www.peerspace.com\/resources\/","name":"Peerspace","description":"Resources &amp; Inspiration to make every moment worth celebrating","publisher":{"@id":"https:\/\/www.peerspace.com\/resources\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.peerspace.com\/resources\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.peerspace.com\/resources\/#organization","name":"Peerspace","url":"https:\/\/www.peerspace.com\/resources\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.peerspace.com\/resources\/#\/schema\/logo\/image\/","url":"https:\/\/www.peerspace.com\/resources\/wp-content\/uploads\/320180448_537730991614706_6776666821941108653_n.jpg","contentUrl":"https:\/\/www.peerspace.com\/resources\/wp-content\/uploads\/320180448_537730991614706_6776666821941108653_n.jpg","width":800,"height":800,"caption":"Peerspace"},"image":{"@id":"https:\/\/www.peerspace.com\/resources\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/peerspace","https:\/\/x.com\/peerspace","https:\/\/instagram.com\/peerspace","https:\/\/www.linkedin.com\/company\/peerspace\/","https:\/\/www.pinterest.com\/peerspace\/","https:\/\/www.youtube.com\/channel\/UCUP7_kldWXa7zRDge66pKfw"]}]}},"_links":{"self":[{"href":"https:\/\/www.peerspace.com\/resources\/wp-json\/wp\/v2\/tags\/29","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.peerspace.com\/resources\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.peerspace.com\/resources\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.peerspace.com\/resources\/wp-json\/wp\/v2\/posts?tags=29"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}